{"id":4201,"date":"2020-09-09T07:49:42","date_gmt":"2020-09-09T06:49:42","guid":{"rendered":"https:\/\/floor-dynamics.com\/?p=4201"},"modified":"2020-09-09T09:24:54","modified_gmt":"2020-09-09T08:24:54","slug":"effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots","status":"publish","type":"post","link":"https:\/\/floor-dynamics.com\/fr\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\/","title":{"rendered":"Effet de la r\u00e9gularit\u00e9 de la surface du sol sur la robotisation des entrep\u00f4ts"},"content":{"rendered":"\n<p><strong><em>\u00ab\u00a0La r\u00e9gularit\u00e9 n&rsquo;a que deux amis, le professionnalisme et le succ\u00e8s\u00a0\u00bb<\/em><\/strong><\/p>\n\n\n\n<p>Dans un monde de la logistique en \u00e9volution rapide, les entrep\u00f4ts automatis\u00e9s sont en plein essor. Stimul\u00e9es par la croissance du commerce \u00e9lectronique et notre demande de d\u00e9lais de livraison de plus en plus courts, les entreprises utilisent des <strong>robots mobiles autonomes<\/strong> (<strong>AMR<\/strong>) pour stocker et r\u00e9cup\u00e9rer les produits par r\u00e9f\u00e9rence unitaire. Le syst\u00e8me popularis\u00e9 sous le nom de <strong>P2P<\/strong> ou pick-to-person, utilise de petits robots pour transporter des nacelles ou des \u00e9tag\u00e8res mobiles d&rsquo;une zone de stockage \u00e0 une station de pr\u00e9l\u00e8vement et d\u2019emballage.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"679\" src=\"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/09\/article-1-1fr-1024x679.jpg\" alt=\"\" class=\"wp-image-4202\" srcset=\"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/09\/article-1-1fr-1024x679.jpg 1024w, https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/09\/article-1-1fr-640x424.jpg 640w, https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/09\/article-1-1fr-768x509.jpg 768w, https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/09\/article-1-1fr.jpg 1517w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>\u00a9EXOTEC \u2013 Skypod\u00ae<\/figcaption><\/figure>\n\n\n\n<p>\u00c0 premi\u00e8re vue, on n\u2019imaginerait pas que les exigences de r\u00e9gularit\u00e9 de surface des sols pour ces AMR soient tr\u00e8s \u00e9lev\u00e9es. Apr\u00e8s tout, la hauteur totale (robot \u2013 bac) n&rsquo;est que de l&rsquo;ordre d\u2019un ou deux m\u00e8tres et les charges sont \u00e9galement limit\u00e9es. Cependant, la g\u00e9om\u00e9trie et la mani\u00e8re dont ces v\u00e9hicules fonctionnent sont tr\u00e8s diff\u00e9rentes de celles d&rsquo;un chariot \u00e9l\u00e9vateur \u00e0 fourche ou d&rsquo;un trilat\u00e9ral pour all\u00e9es \u00e9troites (VNA).<\/p>\n\n\n\n<p>Les configurations des syst\u00e8mes robotiques varient consid\u00e9rablement. Alors que certains fonctionnent selon un mod\u00e8le de libre circulation, beaucoup circulent sur une grille strictement d\u00e9termin\u00e9e (x-y). Les vitesses de d\u00e9placement pour ce dernier peuvent \u00eatre nettement plus rapides. Un robot P2P typique se compose d&rsquo;un essieu moteur central et de quatre roues pivotantes &#8211; une \u00e0 chaque coin. Pour emporter un bac, le robot tourne autour de son axe. Ils sont parfois guid\u00e9s par un laser qui inspecte la surface et se rep\u00e8re sur des codes QRC positionn\u00e9s au sol. Toutes ces caract\u00e9ristiques tr\u00e8s sp\u00e9cifiques imposent non seulement certaines conditions de r\u00e9gularit\u00e9 de surface, mais \u00e9galement des propri\u00e9t\u00e9s particuli\u00e8res telles que la <strong>rugosit\u00e9<\/strong> de surface et la r\u00e9sistance \u00e0 l&rsquo;abrasion et au ripage ainsi qu\u2019un \u00e9tat de <strong>brillance<\/strong>.<\/p>\n\n\n\n<p>En termes de r\u00e9gularit\u00e9 de surface, deux cas particuliers posent probl\u00e8mes pour un parfait fonctionnement de ces robots. Il s&rsquo;agit d&rsquo;une courbure concave et convexe, qui peut \u00eatre d\u00e9finie comme un taux d&rsquo;erreur de changement sur une longueur d&rsquo;onde courte et \/ ou moyenne.<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>En cas d&rsquo;erreur convexe, le v\u00e9hicule n&rsquo;est plus support\u00e9 par les roues pivotantes ce qui induit un basculement autour de l&rsquo;essieu central<\/li><li>Pour les erreurs concaves, l&rsquo;essieu central peut devenir suspendu et perdre la traction. On doit particuli\u00e8rement se pr\u00e9occuper de ce ph\u00e9nom\u00e8ne sur les planchers<\/li><li>Sur une plus grande longueur d&rsquo;onde, des erreurs concaves peuvent conduire \u00e0 des chocs entre des v\u00e9hicules circulant en parall\u00e8le<\/li><\/ol>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"467\" src=\"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/09\/article-1-2-1024x467.jpg\" alt=\"\" class=\"wp-image-4226\" srcset=\"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/09\/article-1-2-1024x467.jpg 1024w, https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/09\/article-1-2-640x292.jpg 640w, https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/09\/article-1-2-768x350.jpg 768w, https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/09\/article-1-2.jpg 1316w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Compte tenu du co\u00fbt direct et indirect de ces \u00e9quipements et du fait qu\u2019ils circulent de mani\u00e8re continue sur l\u2019ensemble des installations, la r\u00e9gularit\u00e9 doit \u00eatre obtenue <strong>en tout point du dallage<\/strong> et non en moyenne de mani\u00e8re statistique comme les normes actuelles le permettent.<\/p>\n\n\n\n<p>L\u2019entreprise Floor Dynamics a d\u00e9velopp\u00e9 une technologie bas\u00e9e sur un relev\u00e9 <strong>Laserscan 3D<\/strong> coupl\u00e9 avec un logiciel d\u2019analyse de donn\u00e9es <strong>Pellego\u2122<\/strong> pour produire une cartographie haute d\u00e9finition de toute la surface du sol.<\/p>\n\n\n\n<p>En la mettant en \u0153uvre durant la construction, Floor Dynamics permet d\u2019acc\u00e9l\u00e9rer la phase d\u2019ex\u00e9cution du sol et la mise en service du syst\u00e8me de robots. Cette approche peut \u00eatre \u00e9galement utilis\u00e9e apr\u00e8s la r\u00e9alisation du dallage pour certifier le respect de la sp\u00e9cification ou en cas de d\u00e9fauts, pour identifier et quantifier les zones \u00e0 reprendre en pon\u00e7age.<\/p>\n\n\n\n<p>Cette nouvelle notion de <strong>r\u00e9gularit\u00e9 de surface en tout point<\/strong> est \u00e0 prendre en compte avant tout investissement dans un syst\u00e8me robotis\u00e9 afin d\u2019\u00e9viter les d\u00e9convenues d\u2019une perte de productivit\u00e9 de la flotte d\u2019AMR et de travaux fastidieux et co\u00fbteux de reprise ponctuelle ou g\u00e9n\u00e9ralis\u00e9e de la plan\u00e9it\u00e9 du dallage.<\/p>\n\n\n\n<p><strong>Christophe Cortinovis<\/strong><br>D\u2019apr\u00e8s l\u2019article en anglais de Andrew Keen &#8211; CSO RCR Flooring Services<\/p>\n\n\n\n<p><a href=\"http:\/\/www.floordynamics.com\/fr\">www.floordynamics.com\/fr<\/a> &nbsp;<br><a href=\"http:\/\/www.monofloor.fr\">www.monofloor.fr<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0La r\u00e9gularit\u00e9 n&rsquo;a que deux amis, le professionnalisme et le succ\u00e8s\u00a0\u00bb Dans un monde de la logistique en \u00e9volution rapide, les entrep\u00f4ts automatis\u00e9s sont en plein essor. Stimul\u00e9es par la croissance du commerce \u00e9lectronique et notre demande de d\u00e9lais de&#8230;<\/p>\n","protected":false},"author":5,"featured_media":4209,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[41],"tags":[],"class_list":["post-4201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles-techniques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Effet de la r\u00e9gularit\u00e9 de la surface du sol sur la robotisation des entrep\u00f4ts - Floor Dynamics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/floor-dynamics.com\/fr\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Effet de la r\u00e9gularit\u00e9 de la surface du sol sur la robotisation des entrep\u00f4ts - Floor Dynamics\" \/>\n<meta property=\"og:description\" content=\"\u00ab\u00a0La r\u00e9gularit\u00e9 n&rsquo;a que deux amis, le professionnalisme et le succ\u00e8s\u00a0\u00bb Dans un monde de la logistique en \u00e9volution rapide, les entrep\u00f4ts automatis\u00e9s sont en plein essor. Stimul\u00e9es par la croissance du commerce \u00e9lectronique et notre demande de d\u00e9lais de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/floor-dynamics.com\/fr\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\/\" \/>\n<meta property=\"og:site_name\" content=\"Floor Dynamics\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-09T06:49:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-09T08:24:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/06\/article-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1316\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David Carrasco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Carrasco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\\\/\"},\"author\":{\"name\":\"David Carrasco\",\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/#\\\/schema\\\/person\\\/fb2f63944fac34fd2dd8d8fdd5e23a5f\"},\"headline\":\"Effet de la r\u00e9gularit\u00e9 de la surface du sol sur la robotisation des entrep\u00f4ts\",\"datePublished\":\"2020-09-09T06:49:42+00:00\",\"dateModified\":\"2020-09-09T08:24:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\\\/\"},\"wordCount\":738,\"image\":{\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/floor-dynamics.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/article-1.jpg\",\"articleSection\":[\"Articles techniques\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\\\/\",\"url\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\\\/\",\"name\":\"Effet de la r\u00e9gularit\u00e9 de la surface du sol sur la robotisation des entrep\u00f4ts - Floor Dynamics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/floor-dynamics.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/article-1.jpg\",\"datePublished\":\"2020-09-09T06:49:42+00:00\",\"dateModified\":\"2020-09-09T08:24:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/#\\\/schema\\\/person\\\/fb2f63944fac34fd2dd8d8fdd5e23a5f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\\\/#primaryimage\",\"url\":\"https:\\\/\\\/floor-dynamics.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/article-1.jpg\",\"contentUrl\":\"https:\\\/\\\/floor-dynamics.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/article-1.jpg\",\"width\":1316,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Effet de la r\u00e9gularit\u00e9 de la surface du sol sur la robotisation des entrep\u00f4ts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/\",\"name\":\"Floor Dynamics\",\"description\":\"Understanding Floors. Optimising Logistics.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/#\\\/schema\\\/person\\\/fb2f63944fac34fd2dd8d8fdd5e23a5f\",\"name\":\"David Carrasco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bffb59f9545a40dcc56e3f6ea27123939c1e2f25629a316f9f4d8429895baaf1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bffb59f9545a40dcc56e3f6ea27123939c1e2f25629a316f9f4d8429895baaf1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bffb59f9545a40dcc56e3f6ea27123939c1e2f25629a316f9f4d8429895baaf1?s=96&d=mm&r=g\",\"caption\":\"David Carrasco\"},\"url\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/author\\\/david-carrascorcrif-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Effet de la r\u00e9gularit\u00e9 de la surface du sol sur la robotisation des entrep\u00f4ts - Floor Dynamics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/floor-dynamics.com\/fr\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\/","og_locale":"fr_FR","og_type":"article","og_title":"Effet de la r\u00e9gularit\u00e9 de la surface du sol sur la robotisation des entrep\u00f4ts - Floor Dynamics","og_description":"\u00ab\u00a0La r\u00e9gularit\u00e9 n&rsquo;a que deux amis, le professionnalisme et le succ\u00e8s\u00a0\u00bb Dans un monde de la logistique en \u00e9volution rapide, les entrep\u00f4ts automatis\u00e9s sont en plein essor. Stimul\u00e9es par la croissance du commerce \u00e9lectronique et notre demande de d\u00e9lais de...","og_url":"https:\/\/floor-dynamics.com\/fr\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\/","og_site_name":"Floor Dynamics","article_published_time":"2020-09-09T06:49:42+00:00","article_modified_time":"2020-09-09T08:24:54+00:00","og_image":[{"width":1316,"height":600,"url":"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/06\/article-1.jpg","type":"image\/jpeg"}],"author":"David Carrasco","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"David Carrasco","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/floor-dynamics.com\/fr\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\/#article","isPartOf":{"@id":"https:\/\/floor-dynamics.com\/fr\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\/"},"author":{"name":"David Carrasco","@id":"https:\/\/floor-dynamics.com\/fr\/#\/schema\/person\/fb2f63944fac34fd2dd8d8fdd5e23a5f"},"headline":"Effet de la r\u00e9gularit\u00e9 de la surface du sol sur la robotisation des entrep\u00f4ts","datePublished":"2020-09-09T06:49:42+00:00","dateModified":"2020-09-09T08:24:54+00:00","mainEntityOfPage":{"@id":"https:\/\/floor-dynamics.com\/fr\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\/"},"wordCount":738,"image":{"@id":"https:\/\/floor-dynamics.com\/fr\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\/#primaryimage"},"thumbnailUrl":"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/06\/article-1.jpg","articleSection":["Articles techniques"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/floor-dynamics.com\/fr\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\/","url":"https:\/\/floor-dynamics.com\/fr\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\/","name":"Effet de la r\u00e9gularit\u00e9 de la surface du sol sur la robotisation des entrep\u00f4ts - Floor Dynamics","isPartOf":{"@id":"https:\/\/floor-dynamics.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/floor-dynamics.com\/fr\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\/#primaryimage"},"image":{"@id":"https:\/\/floor-dynamics.com\/fr\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\/#primaryimage"},"thumbnailUrl":"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/06\/article-1.jpg","datePublished":"2020-09-09T06:49:42+00:00","dateModified":"2020-09-09T08:24:54+00:00","author":{"@id":"https:\/\/floor-dynamics.com\/fr\/#\/schema\/person\/fb2f63944fac34fd2dd8d8fdd5e23a5f"},"breadcrumb":{"@id":"https:\/\/floor-dynamics.com\/fr\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/floor-dynamics.com\/fr\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/floor-dynamics.com\/fr\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\/#primaryimage","url":"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/06\/article-1.jpg","contentUrl":"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/06\/article-1.jpg","width":1316,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/floor-dynamics.com\/fr\/effet-de-la-regularite-de-la-surface-du-sol-sur-la-robotisation-des-entrepots\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/floor-dynamics.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Effet de la r\u00e9gularit\u00e9 de la surface du sol sur la robotisation des entrep\u00f4ts"}]},{"@type":"WebSite","@id":"https:\/\/floor-dynamics.com\/fr\/#website","url":"https:\/\/floor-dynamics.com\/fr\/","name":"Floor Dynamics","description":"Understanding Floors. Optimising Logistics.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/floor-dynamics.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/floor-dynamics.com\/fr\/#\/schema\/person\/fb2f63944fac34fd2dd8d8fdd5e23a5f","name":"David Carrasco","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/bffb59f9545a40dcc56e3f6ea27123939c1e2f25629a316f9f4d8429895baaf1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bffb59f9545a40dcc56e3f6ea27123939c1e2f25629a316f9f4d8429895baaf1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bffb59f9545a40dcc56e3f6ea27123939c1e2f25629a316f9f4d8429895baaf1?s=96&d=mm&r=g","caption":"David Carrasco"},"url":"https:\/\/floor-dynamics.com\/fr\/author\/david-carrascorcrif-com\/"}]}},"_links":{"self":[{"href":"https:\/\/floor-dynamics.com\/fr\/wp-json\/wp\/v2\/posts\/4201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/floor-dynamics.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/floor-dynamics.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/floor-dynamics.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/floor-dynamics.com\/fr\/wp-json\/wp\/v2\/comments?post=4201"}],"version-history":[{"count":3,"href":"https:\/\/floor-dynamics.com\/fr\/wp-json\/wp\/v2\/posts\/4201\/revisions"}],"predecessor-version":[{"id":4229,"href":"https:\/\/floor-dynamics.com\/fr\/wp-json\/wp\/v2\/posts\/4201\/revisions\/4229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/floor-dynamics.com\/fr\/wp-json\/wp\/v2\/media\/4209"}],"wp:attachment":[{"href":"https:\/\/floor-dynamics.com\/fr\/wp-json\/wp\/v2\/media?parent=4201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/floor-dynamics.com\/fr\/wp-json\/wp\/v2\/categories?post=4201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/floor-dynamics.com\/fr\/wp-json\/wp\/v2\/tags?post=4201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}