{"id":4444,"date":"2020-10-19T14:17:19","date_gmt":"2020-10-19T13:17:19","guid":{"rendered":"https:\/\/floor-dynamics.com\/?p=4444"},"modified":"2020-10-20T08:45:44","modified_gmt":"2020-10-20T07:45:44","slug":"sols-industriels-en-beton-du-21eme-siecle","status":"publish","type":"post","link":"https:\/\/floor-dynamics.com\/fr\/sols-industriels-en-beton-du-21eme-siecle\/","title":{"rendered":"Sols industriels en b\u00e9ton du 21\u00e8me si\u00e8cle"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"973\" height=\"582\" src=\"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/Floors-21st-Century-FD.png\" alt=\"\" class=\"wp-image-4464\" srcset=\"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/Floors-21st-Century-FD.png 973w, https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/Floors-21st-Century-FD-640x383.png 640w, https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/Floors-21st-Century-FD-768x459.png 768w\" sizes=\"auto, (max-width: 973px) 100vw, 973px\" \/><figcaption>\u201cFly across the city, rise above the land, you can do almost everything. Now you\u2019re a 21st century man\u201d &#8211; Jeff Lyne<br><\/figcaption><\/figure><\/div>\n\n\n\n<p><strong>Contr\u00f4le de r\u00e9gularit\u00e9 de surface des sols industriels<\/strong><\/p>\n\n\n\n<p>Depuis plus de 40 ans, les directives et standards de construction concernant les dallages en b\u00e9ton sur terre plein recommandent que les sols soient con\u00e7us, construits et mesur\u00e9s en tenant compte du mouvement et de la direction des \u00e9quipements de manutention, tels que les chariots \u00e9l\u00e9vateurs.<\/p>\n\n\n\n<p>Des tol\u00e9rances de libre circulation ont \u00e9t\u00e9 introduites pour les dallages sur lesquels les chariots \u00e9l\u00e9vateurs peuvent tourner et se d\u00e9placer de fa\u00e7on libre et al\u00e9atoire, et des tol\u00e9rances de mouvement d\u00e9fini ont \u00e9t\u00e9 \u00e9tablies pour les sols o\u00f9 les engins de manutention sont limit\u00e9s \u00e0 se d\u00e9placer sur un seul trajet, g\u00e9n\u00e9ralement dans une all\u00e9e tr\u00e8s \u00e9troite (VNA). Pour les dallages \u00e0 mouvement libre et d\u00e9fini, les niveaux de tol\u00e9rances ont \u00e9t\u00e9 conditionn\u00e9s principalement par &nbsp;la hauteur des syst\u00e8mes de rayonnage.<\/p>\n\n\n\n<p>Il y a plus de 30 ans, aux \u00c9tats-Unis, le syst\u00e8me des num\u00e9ros F \u00e9tait valid\u00e9 par l&rsquo;Institut Am\u00e9ricain du B\u00e9ton (ACI) comme le moyen de contr\u00f4ler la plan\u00e9it\u00e9 des sols \u00e0 mouvement libre. Les recommendations techniques britanniques de la TR34 ont introduit des limites de tol\u00e9rance pour la r\u00e9gularit\u00e9 de surface. Le Royaume-Uni et les \u00c9tats-Unis ont adopt\u00e9 une repr\u00e9sentation statistique pour les sols \u00e0 libre circulation, en admettant deux limites:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>la mesure de la surface totale du sol pour chaque combinaison possible de sens de la circulation n&rsquo;est tout simplement pas r\u00e9alisable<\/li><li>l\u2019exactitude des \u00e9quipement de contr\u00f4le (rapport\u00e9e par les fabricants) n&rsquo;est pas appropri\u00e9e aux moyens de caract\u00e9risation pour les \u00e9quipements de manutention (TR34 2e \u00e9dition, 1994)<\/li><\/ul>\n\n\n\n<p>Lors de la mesure d&rsquo;un mouvement d\u00e9fini, Europ\u00e9ens et Am\u00e9ricains ont adopt\u00e9 le profilographe comme moyen de collecter des donn\u00e9es dans les traces des roues d&rsquo;un chariot \u00e9l\u00e9vateur. Les \u00e9volutions \u00e9lectroniques de ces premiers appareils des ann\u00e9es 70 sont toujours couramment utilis\u00e9s.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"397\" height=\"354\" src=\"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-01_FRA.jpg\" alt=\"\" class=\"wp-image-4445\"\/><figcaption>Profilographe Digital conduit sur une ligne de contr\u00f4le<\/figcaption><\/figure><\/div>\n\n\n\n<p><strong>Timing appropri\u00e9 des contr\u00f4les&nbsp;<\/strong><\/p>\n\n\n\n<p>Aux \u00c9tats-Unis et au Royaume-Uni, les tol\u00e9rances des dallages ont \u00e9t\u00e9 \u00e9labor\u00e9es par des groupes de travail de l&rsquo;industrie de la construction comprenant des membres de divers fabricants de chariots.<\/p>\n\n\n\n<p>Reconnaissant l&rsquo;\u00e9quilibre entre la construction d&rsquo;un sol avec un mat\u00e9riau qui est sujet au retrait, au curling, au fluage, au tassement et \u00e0 la d\u00e9formation sous charges, les directives am\u00e9ricaines et britanniques ont pr\u00e9cis\u00e9 un calendrier normatif des prises de mesures.<\/p>\n\n\n\n<p>Les \u00c9tats-Unis ont introduit une fen\u00eatre de 72 heures apr\u00e8s construction de la dalle. Au Royaume-Uni, TR34 2e \u00e9dition a not\u00e9 que \u00ables controles doivent \u00eatre effectu\u00e9s, si possible, le lendemain du coulage du b\u00e9ton\u00bb. La derni\u00e8re \u00e9dition du TR34 (4\u00e8me) accepte d\u00e9sormais que 30 jours soient autoris\u00e9s, mais n\u00e9anmoins, ces dispositions impliquent invariablement que le dallage changera avec le temps, et ce qui est prouv\u00e9 conforme aujourd&rsquo;hui par un contr\u00f4le peut ne pas respecter les m\u00eames tol\u00e9rances \u00e0 l&rsquo;avenir.<\/p>\n\n\n\n<p><strong>\u00c9volutions de la logistique au cours du temps<\/strong><\/p>\n\n\n\n<p>Depuis les ann\u00e9es 1990, l&rsquo;utilisation des sols industriels a beaucoup \u00e9volu\u00e9. Pouss\u00e9 par la demande des consommateurs, le secteur de la logistique repousse les limites de l&rsquo;offre. Les racks sont mont\u00e9s plus haut, les chariots sont devenus plus rapidez, avec des roues plus dures et plus agressives pour les surfaces, l\u2019intensit\u00e9 du trafic dans les entrep\u00f4ts a \u00e9t\u00e9 multipli\u00e9e avec la g\u00e9n\u00e9ralisation du 24\/7.<\/p>\n\n\n\n<p>En parall\u00e8le, les programmes de construction ont \u00e9t\u00e9 raccourcis. L\u2019usage de la Laserscreed\u00ae s\u2019est r\u00e9pandu , apportant la qualit\u00e9 et productivit\u00e9 par une construction m\u00e9canis\u00e9e en phase avec la demande du secteur logistique. Le r\u00e9sultat a \u00e9t\u00e9 une construction acc\u00e9l\u00e9r\u00e9e et des productions journali\u00e8res de plusieurs milliers de m\u00e8tres carr\u00e9s par jour, avec des tol\u00e9rances de niveau et de plan\u00e9it\u00e9 de plus en plus restrictives.<\/p>\n\n\n\n<p><strong>Logistique du 21\u00e8me si\u00e8cle<\/strong><\/p>\n\n\n\n<p>Pouss\u00e9 une nouvelle fois par la demande des consommateurs, l&rsquo;environnement logistique \u00e9volue encore, de fa\u00e7on tr\u00e8s brutale avec l\u2019irruption du e-commerce. L\u2019individualisation des livraisons directement au consommateur final chamboule l\u2019organisation des entrep\u00f4ts. La hauteur et la compacit\u00e9 des rayonnages n&rsquo;est plus le facteur d\u00e9terminant. C\u2019est la circulation multidirectionnelle sur des \u00e9tages entiers qui devient la nouvelle norme. Les b\u00e2timents logistiques s\u2019enrichissent de plusieurs \u00e9tages. Dans ce contexte, les tol\u00e9rances des sols ne sont plus guid\u00e9s par la hauteur des racks. Le contr\u00f4les statistiques ne r\u00e9pondent plus au besoin des utilisateurs lorsque les exigences des nouveaux engins de manutention autonomes parcourent l\u2019ensemble de l\u2019entrep\u00f4t. Si une zone non contr\u00f4l\u00e9e d\u00e9passe les tol\u00e9rances n\u00e9cessaires, l\u2019ensemble du syst\u00e8me de gesti\u00f3n logistique est affect\u00e9 avec des cons\u00e9quences importantes sur la productivit\u00e9 du site. En r\u00e9sum\u00e9, les limites de r\u00e9gularit\u00e9 de surface d\u00e9finies pour les v\u00e9hicules guid\u00e9s automatiques doivent \u00eatre respect\u00e9es en tout point et en tout temps.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-02_FRA-1024x683.jpg\" alt=\"\" class=\"wp-image-4448\" srcset=\"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-02_FRA-1024x683.jpg 1024w, https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-02_FRA-640x427.jpg 640w, https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-02_FRA-768x512.jpg 768w, https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-02_FRA-272x182.jpg 272w, https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-02_FRA.jpg 1141w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Scanner Laser 3D utilis\u00e9 pour la collecte des donn\u00e9es pour une cartographie haute definition \u00a9Floor Dynamics<\/figcaption><\/figure>\n\n\n\n<p><strong>Comment mesurer des sp\u00e9cifications sur mesure ?<\/strong><\/p>\n\n\n\n<p>Le bureau de consultants en sols industriels Monofloor a fourni des conseils sp\u00e9cialis\u00e9s en dalles de sol et des audits de qualit\u00e9 tout au long de la construction pour plusieurs millions de m\u00e8tres carr\u00e9s de dallages de plateformes logistiques destin\u00e9es au e-commerce .<\/p>\n\n\n\n<p>Dans un march\u00e9 bas\u00e9 sur la rapidit\u00e9 de livraison, nous avons vu diff\u00e9rentes approches utilis\u00e9es pour mesurer et valider la conformit\u00e9 aux sp\u00e9cifications sur mesure adopt\u00e9es par le secteur.<\/p>\n\n\n\n<p>Nous avons d\u2019abord assist\u00e9 \u00e0 l&rsquo;adoption des m\u00e9thodes de contr\u00f4le par profilographe pour \u00e9valuer la conformit\u00e9 d&rsquo;une sp\u00e9cification sur mesure. Sur un projet r\u00e9cent, 54 jours de coulage ont \u00e9t\u00e9 programm\u00e9s pour les dallages sur 3 niveaux de planchers . Pour valider la conformit\u00e9 aux sp\u00e9cifications, le profilographe a \u00e9t\u00e9 utlis\u00e9 pour pr\u00e8s de 140 kilom\u00e8tres de profils sur la surface des sols nouvellement construits.<\/p>\n\n\n\n<p>Il a fallu presque autant de temps que la dur\u00e9e de construction pour \u00e9tudier, analyser, rectifier la tol\u00e9rance et valider le travail effectu\u00e9 \u00e0 l&rsquo;aide de la m\u00e9thode du profilographe.<\/p>\n\n\n\n<p>36 jours ont \u00e9t\u00e9 n\u00e9cessaires avant que la validation des 15 premi\u00e8res coul\u00e9es ne soit r\u00e9alis\u00e9e. De la premi\u00e8re mesure au profilographe jusqu\u2019au rapport final, environ 90 jours ont \u00e9t\u00e9 n\u00e9cessaires.<\/p>\n\n\n\n<p>Alors que 140000 m\u00e8tres lin\u00e9aires de sol ont \u00e9t\u00e9 contr\u00f4l\u00e9s, le profilographe n\u2019a mesur\u00e9 dans les faits que les lignes parcourues par ses roues, et par cons\u00e9quent, la grande majorit\u00e9 de la surface du sol reste non mesur\u00e9e. Cela laisse une forte incertitude pour les utilisateurs du b\u00e2timent. Ils doivent esp\u00e9rer que leur entrep\u00f4t automatis\u00e9 sera en mesure de fonctionner \u00e0 100% m\u00eame sur les surfaces non contr\u00f4l\u00e9es.<\/p>\n\n\n\n<p>Nous commen\u00e7ons \u00e0 voir des entreprises adopter la technologie du 21e si\u00e8cle pour construire, \u00e9tudier, analyser, affiner la tol\u00e9rance et contr\u00f4ler les sols. En utilisant des stations totales, des niveaux \u00e9lectroniques et des scanners laser tridimensionnels de haute pr\u00e9cision, des \u00e9tages entiers peuvent \u00eatre inspect\u00e9s plus rapidement qu&rsquo;ils n\u2019ont \u00e9t\u00e9 construits. Des donn\u00e9es int\u00e9grales peuvent \u00eatre trait\u00e9es presque instantan\u00e9ment, ce qui signifie que le pon\u00e7age \u00e0 la bonne tol\u00e9rance peut \u00eatre r\u00e9alis\u00e9e dans les meilleurs d\u00e9lais. Dans une perpective encore plus dynamique, la v\u00e9rification de l\u2019atteinte des tol\u00e9rances peut \u00eatre d\u00e9montr\u00e9e avant que le sol ait fini de durcir, ce qui permet donc des corrections en temps r\u00e9el lors de la construction.<\/p>\n\n\n\n<p>Nous voyons maintenant des panneaux de dalles individuelles inspect\u00e9s, ponc\u00e9s et valid\u00e9s conformes durant la pase de s\u00e8chage du b\u00e9ton. Sur un projet r\u00e9cent, avec le m\u00eame cahier des charges sur mesure, 15 panneaux ont \u00e9t\u00e9 mesur\u00e9s, rectifi\u00e9s et valid\u00e9s en 22 jours gr\u00e2ce aux cartes haute d\u00e9finition qui ont \u00e9t\u00e9 produites.<\/p>\n\n\n\n<p>La figure suivante pr\u00e9sente une comparaison entre les deux chronogrammes.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"473\" src=\"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-03_FRA-1024x473.png\" alt=\"\" class=\"wp-image-4451\" srcset=\"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-03_FRA-1024x473.png 1024w, https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-03_FRA-640x296.png 640w, https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-03_FRA-768x355.png 768w, https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-03_FRA-1536x710.png 1536w, https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-03_FRA.png 1737w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Apr\u00e8s 15 jours de coulage, une gain de 14 jours, de la construction des dallages \u00e0 leur certification, \u00e9t\u00e9 obtenu en utilisant un scanner laser par rapport \u00e0 la m\u00e9thode avec profilographe. Pour 54 coulages, ce sont des mois qui sont ainsi \u00e9conomis\u00e9s sur l\u2019ensemble du programme du projet.<\/p>\n\n\n\n<p>La technologie de balayage par rayon laser est utilis\u00e9e pour v\u00e9rifier les tol\u00e9rances du sol afin que des ajustements puissent \u00eatre apport\u00e9s lorsque le b\u00e9ton est encore plastique. Connu sous le nom de rectification en temps r\u00e9el, ce processus commence \u00e0 \u00eatre utilis\u00e9 par des entreprises sp\u00e9cialis\u00e9es pour r\u00e9duire massivement la quantit\u00e9 de pon\u00e7age final aux tol\u00e9rances requises. Dans de nombreux cas, nous avons vu la n\u00e9cessit\u00e9 de pon\u00e7age post\u00e9rieur compl\u00e8tement supprim\u00e9e.<\/p>\n\n\n\n<p>Des cartes haute d\u00e9finition des sols, comme celle illustr\u00e9e ci dessous, sont utilis\u00e9es pour fournir des informations en temps r\u00e9el aux op\u00e9rateurs de l\u2019\u00e9quipe de construction.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"518\" src=\"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-04_FRA-1024x518.png\" alt=\"\" class=\"wp-image-4454\" srcset=\"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-04_FRA-1024x518.png 1024w, https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-04_FRA-640x324.png 640w, https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-04_FRA-768x389.png 768w, https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-04_FRA.png 1344w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Scan Laser 3D avec rectification de surface en temps r\u00e9el \u00a9Floor Dynamics<\/figcaption><\/figure>\n\n\n\n<p>Cela implique que les tol\u00e9rances de plan\u00e9it\u00e9 atteintes s&rsquo;am\u00e9liorent de fa\u00e7on spectaculaire tandis que des mesures correctives rapides et pr\u00e9cises des travaux sont effectu\u00e9s si n\u00e9cessaire.<\/p>\n\n\n\n<p>L\u2019autre avantage d\u00e9cisif du contr\u00f4le par Scanner Laser 3D est que l\u2019int\u00e9gralit\u00e9 de la Surface est contr\u00f4l\u00e9e, pas seulement dans les traces de roues d&rsquo;un profilographe. Cela garantit aux utilisateurs du b\u00e2timent que leur entrep\u00f4t fonctionnera, quelle que soit la mani\u00e8re dont ils choisiront de l&rsquo;utiliser.<\/p>\n\n\n\n<p><strong>Remarques finales<\/strong><\/p>\n\n\n\n<p>Il a \u00e9t\u00e9 reconnu il y a 30 ans que le manque d\u2019exactitude des \u00e9quipements de mesure de plan\u00e9it\u00e9 pour sols industriels n\u2019en faisait pas un moyen appropri\u00e9 de d\u00e9terminer l&rsquo;ad\u00e9quation entre le sol et les \u00e9quipements de manutention. Monofloor recommande aux g\u00e9om\u00e8tres sp\u00e9cialis\u00e9s de d\u00e9montrer l&rsquo;exactitude, la r\u00e9p\u00e9tabilit\u00e9 et la pr\u00e9cision, que la technologie moderne soit utilis\u00e9e ou non.<\/p>\n\n\n\n<p>Le profilographe a \u00e9t\u00e9 d\u00e9velopp\u00e9 pour une utilisation dans un seul sens, des sols pour trafic \u00e0 mouvements d\u00e9finis et dans ce domaine, il a fait ses preuves. Cependant, il est clair que les dallages pour circulation multidirectionnellle n\u00e9cessitent une approche diff\u00e9rente des m\u00e9thodes d\u2019\u00e9valuation. Il est imp\u00e9ratif d\u2019acc\u00e9l\u00e9rer le contr\u00f4le de conformit\u00e9 sans perdre en pertinence et justesse des conclusions.<\/p>\n\n\n\n<p>En utilisant la technologie du 21e si\u00e8cle, les sp\u00e9cifications de dalles de plancher sur mesure peuvent \u00eatre mesur\u00e9es et valid\u00e9es rapidement et les programmes de construction sont r\u00e9duits massivement. En son temps, le Laserscreed\u00ae a permis de construire de grandes surfaces de dallages \u00e0 une vitesse et pour un niveau de qualit\u00e9 sans pr\u00e9c\u00e9dent. Aujourd\u2019hui, le scanner laser tridimensionnel permet de mettre en service de grandes surfaces de sol en un temps in\u00e9gal\u00e9 et en respectant les nouvelles exigences des acteurs logistiques du e-commerce.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-05_FRA-1024x658.png\" alt=\"\" class=\"wp-image-4457\" width=\"580\" height=\"372\" srcset=\"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-05_FRA-1024x658.png 1024w, https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-05_FRA-640x411.png 640w, https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-05_FRA-768x494.png 768w, https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-05_FRA-1536x987.png 1536w, https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/article6-05_FRA.png 1738w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><figcaption>Cartographie de contour Haute D\u00e9finition r\u00e9alis\u00e9e par Pellego\u2122 <br>\u00a9Floor Dynamics<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-right\"><strong>Christophe Cortinovis \u2013 COO RCR Industrial Flooring<\/strong><br>Traduit de l\u2019article r\u00e9dig\u00e9 par Tom Hancock, directeur Monofloor UK publi\u00e9 dans le magazine \u201cConcrete Magazine\u201d de Septembre 2020<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>R\u00c9F\u00c9RENCES BIBLIOGRAPHIQUES :<br>Concrete Society &#8211; Technical Report 34 2e \u00e9dition, The Concrete Society, Camberley, 1994<br>Concrete Society &#8211; Technical Report 34 4e \u00e9dition, The Concrete Society, Camberley, 2014<br>ACI 117-10 &#8211; Sp\u00e9cification des tol\u00e9rances pour la construction et les mat\u00e9riaux en b\u00e9ton, American Concrete Institute, Farmington Hills, MI, 2010<br>ASTM E1155-96 &#8211; M\u00e9thode d&rsquo;essai standard pour d\u00e9terminer la plan\u00e9it\u00e9 du sol (FF) et les num\u00e9ros de niveau du sol FL, ASTM International, West Conshocken, PA, 2001<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Contr\u00f4le de r\u00e9gularit\u00e9 de surface des sols industriels Depuis plus de 40 ans, les directives et standards de construction concernant les dallages en b\u00e9ton sur terre plein recommandent que les sols soient con\u00e7us, construits et mesur\u00e9s en tenant compte du&#8230;<\/p>\n","protected":false},"author":5,"featured_media":4464,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-4444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sols industriels en b\u00e9ton du 21\u00e8me si\u00e8cle - Floor Dynamics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/floor-dynamics.com\/fr\/sols-industriels-en-beton-du-21eme-siecle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sols industriels en b\u00e9ton du 21\u00e8me si\u00e8cle - Floor Dynamics\" \/>\n<meta property=\"og:description\" content=\"Contr\u00f4le de r\u00e9gularit\u00e9 de surface des sols industriels Depuis plus de 40 ans, les directives et standards de construction concernant les dallages en b\u00e9ton sur terre plein recommandent que les sols soient con\u00e7us, construits et mesur\u00e9s en tenant compte du...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/floor-dynamics.com\/fr\/sols-industriels-en-beton-du-21eme-siecle\/\" \/>\n<meta property=\"og:site_name\" content=\"Floor Dynamics\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-19T13:17:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-20T07:45:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/Floors-21st-Century-FD.png\" \/>\n\t<meta property=\"og:image:width\" content=\"973\" \/>\n\t<meta property=\"og:image:height\" content=\"582\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"David Carrasco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Carrasco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/sols-industriels-en-beton-du-21eme-siecle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/sols-industriels-en-beton-du-21eme-siecle\\\/\"},\"author\":{\"name\":\"David Carrasco\",\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/#\\\/schema\\\/person\\\/fb2f63944fac34fd2dd8d8fdd5e23a5f\"},\"headline\":\"Sols industriels en b\u00e9ton du 21\u00e8me si\u00e8cle\",\"datePublished\":\"2020-10-19T13:17:19+00:00\",\"dateModified\":\"2020-10-20T07:45:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/sols-industriels-en-beton-du-21eme-siecle\\\/\"},\"wordCount\":2069,\"image\":{\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/sols-industriels-en-beton-du-21eme-siecle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/floor-dynamics.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Floors-21st-Century-FD.png\",\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/sols-industriels-en-beton-du-21eme-siecle\\\/\",\"url\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/sols-industriels-en-beton-du-21eme-siecle\\\/\",\"name\":\"Sols industriels en b\u00e9ton du 21\u00e8me si\u00e8cle - Floor Dynamics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/sols-industriels-en-beton-du-21eme-siecle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/sols-industriels-en-beton-du-21eme-siecle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/floor-dynamics.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Floors-21st-Century-FD.png\",\"datePublished\":\"2020-10-19T13:17:19+00:00\",\"dateModified\":\"2020-10-20T07:45:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/#\\\/schema\\\/person\\\/fb2f63944fac34fd2dd8d8fdd5e23a5f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/sols-industriels-en-beton-du-21eme-siecle\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/sols-industriels-en-beton-du-21eme-siecle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/sols-industriels-en-beton-du-21eme-siecle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/floor-dynamics.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Floors-21st-Century-FD.png\",\"contentUrl\":\"https:\\\/\\\/floor-dynamics.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Floors-21st-Century-FD.png\",\"width\":973,\"height\":582},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/sols-industriels-en-beton-du-21eme-siecle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sols industriels en b\u00e9ton du 21\u00e8me si\u00e8cle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/\",\"name\":\"Floor Dynamics\",\"description\":\"Understanding Floors. Optimising Logistics.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/#\\\/schema\\\/person\\\/fb2f63944fac34fd2dd8d8fdd5e23a5f\",\"name\":\"David Carrasco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bffb59f9545a40dcc56e3f6ea27123939c1e2f25629a316f9f4d8429895baaf1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bffb59f9545a40dcc56e3f6ea27123939c1e2f25629a316f9f4d8429895baaf1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bffb59f9545a40dcc56e3f6ea27123939c1e2f25629a316f9f4d8429895baaf1?s=96&d=mm&r=g\",\"caption\":\"David Carrasco\"},\"url\":\"https:\\\/\\\/floor-dynamics.com\\\/fr\\\/author\\\/david-carrascorcrif-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sols industriels en b\u00e9ton du 21\u00e8me si\u00e8cle - Floor Dynamics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/floor-dynamics.com\/fr\/sols-industriels-en-beton-du-21eme-siecle\/","og_locale":"fr_FR","og_type":"article","og_title":"Sols industriels en b\u00e9ton du 21\u00e8me si\u00e8cle - Floor Dynamics","og_description":"Contr\u00f4le de r\u00e9gularit\u00e9 de surface des sols industriels Depuis plus de 40 ans, les directives et standards de construction concernant les dallages en b\u00e9ton sur terre plein recommandent que les sols soient con\u00e7us, construits et mesur\u00e9s en tenant compte du...","og_url":"https:\/\/floor-dynamics.com\/fr\/sols-industriels-en-beton-du-21eme-siecle\/","og_site_name":"Floor Dynamics","article_published_time":"2020-10-19T13:17:19+00:00","article_modified_time":"2020-10-20T07:45:44+00:00","og_image":[{"width":973,"height":582,"url":"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/Floors-21st-Century-FD.png","type":"image\/png"}],"author":"David Carrasco","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"David Carrasco","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/floor-dynamics.com\/fr\/sols-industriels-en-beton-du-21eme-siecle\/#article","isPartOf":{"@id":"https:\/\/floor-dynamics.com\/fr\/sols-industriels-en-beton-du-21eme-siecle\/"},"author":{"name":"David Carrasco","@id":"https:\/\/floor-dynamics.com\/fr\/#\/schema\/person\/fb2f63944fac34fd2dd8d8fdd5e23a5f"},"headline":"Sols industriels en b\u00e9ton du 21\u00e8me si\u00e8cle","datePublished":"2020-10-19T13:17:19+00:00","dateModified":"2020-10-20T07:45:44+00:00","mainEntityOfPage":{"@id":"https:\/\/floor-dynamics.com\/fr\/sols-industriels-en-beton-du-21eme-siecle\/"},"wordCount":2069,"image":{"@id":"https:\/\/floor-dynamics.com\/fr\/sols-industriels-en-beton-du-21eme-siecle\/#primaryimage"},"thumbnailUrl":"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/Floors-21st-Century-FD.png","articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/floor-dynamics.com\/fr\/sols-industriels-en-beton-du-21eme-siecle\/","url":"https:\/\/floor-dynamics.com\/fr\/sols-industriels-en-beton-du-21eme-siecle\/","name":"Sols industriels en b\u00e9ton du 21\u00e8me si\u00e8cle - Floor Dynamics","isPartOf":{"@id":"https:\/\/floor-dynamics.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/floor-dynamics.com\/fr\/sols-industriels-en-beton-du-21eme-siecle\/#primaryimage"},"image":{"@id":"https:\/\/floor-dynamics.com\/fr\/sols-industriels-en-beton-du-21eme-siecle\/#primaryimage"},"thumbnailUrl":"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/Floors-21st-Century-FD.png","datePublished":"2020-10-19T13:17:19+00:00","dateModified":"2020-10-20T07:45:44+00:00","author":{"@id":"https:\/\/floor-dynamics.com\/fr\/#\/schema\/person\/fb2f63944fac34fd2dd8d8fdd5e23a5f"},"breadcrumb":{"@id":"https:\/\/floor-dynamics.com\/fr\/sols-industriels-en-beton-du-21eme-siecle\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/floor-dynamics.com\/fr\/sols-industriels-en-beton-du-21eme-siecle\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/floor-dynamics.com\/fr\/sols-industriels-en-beton-du-21eme-siecle\/#primaryimage","url":"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/Floors-21st-Century-FD.png","contentUrl":"https:\/\/floor-dynamics.com\/wp-content\/uploads\/2020\/10\/Floors-21st-Century-FD.png","width":973,"height":582},{"@type":"BreadcrumbList","@id":"https:\/\/floor-dynamics.com\/fr\/sols-industriels-en-beton-du-21eme-siecle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/floor-dynamics.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Sols industriels en b\u00e9ton du 21\u00e8me si\u00e8cle"}]},{"@type":"WebSite","@id":"https:\/\/floor-dynamics.com\/fr\/#website","url":"https:\/\/floor-dynamics.com\/fr\/","name":"Floor Dynamics","description":"Understanding Floors. Optimising Logistics.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/floor-dynamics.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/floor-dynamics.com\/fr\/#\/schema\/person\/fb2f63944fac34fd2dd8d8fdd5e23a5f","name":"David Carrasco","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/bffb59f9545a40dcc56e3f6ea27123939c1e2f25629a316f9f4d8429895baaf1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bffb59f9545a40dcc56e3f6ea27123939c1e2f25629a316f9f4d8429895baaf1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bffb59f9545a40dcc56e3f6ea27123939c1e2f25629a316f9f4d8429895baaf1?s=96&d=mm&r=g","caption":"David Carrasco"},"url":"https:\/\/floor-dynamics.com\/fr\/author\/david-carrascorcrif-com\/"}]}},"_links":{"self":[{"href":"https:\/\/floor-dynamics.com\/fr\/wp-json\/wp\/v2\/posts\/4444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/floor-dynamics.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/floor-dynamics.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/floor-dynamics.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/floor-dynamics.com\/fr\/wp-json\/wp\/v2\/comments?post=4444"}],"version-history":[{"count":7,"href":"https:\/\/floor-dynamics.com\/fr\/wp-json\/wp\/v2\/posts\/4444\/revisions"}],"predecessor-version":[{"id":4469,"href":"https:\/\/floor-dynamics.com\/fr\/wp-json\/wp\/v2\/posts\/4444\/revisions\/4469"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/floor-dynamics.com\/fr\/wp-json\/wp\/v2\/media\/4464"}],"wp:attachment":[{"href":"https:\/\/floor-dynamics.com\/fr\/wp-json\/wp\/v2\/media?parent=4444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/floor-dynamics.com\/fr\/wp-json\/wp\/v2\/categories?post=4444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/floor-dynamics.com\/fr\/wp-json\/wp\/v2\/tags?post=4444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}